{"id":170373,"date":"2023-12-09T01:10:53","date_gmt":"2023-12-09T07:10:53","guid":{"rendered":"https:\/\/www.pwtorch.com\/site\/?post_type=podcast&#038;p=170373"},"modified":"2023-12-09T01:10:53","modified_gmt":"2023-12-09T07:10:53","slug":"vip-audio-12-9-wkpwp-interview-classic-10-yrs-ago-ad-free-ex-wwe-creative-team-member-chris-dejoseph-on-how-triple-h-differs-from-vince-creatively-benoit-conspiracies-stephanies-new","status":"publish","type":"podcast","link":"https:\/\/www.pwtorch.com\/site\/podcast\/vip-audio-12-9-wkpwp-interview-classic-10-yrs-ago-ad-free-ex-wwe-creative-team-member-chris-dejoseph-on-how-triple-h-differs-from-vince-creatively-benoit-conspiracies-stephanies-new\/","title":{"rendered":"VIP AUDIO 12\/9 \u2013 WKPWP Interview Classic (10 Yrs Ago) (AD-FREE): Ex-WWE Creative Team Member Chris DeJoseph on how Triple H differs from Vince creatively, Benoit conspiracies, Stephanie&#8217;s new title, WWE Network plans, WM30 line-up (81 min.)"},"content":{"rendered":"<div id=\"pwtor-4218073282\" class=\"pwtor-before-content pwtor-entity-placement\"><hr \/><b>SPOTLIGHTED PODCAST ALERT (YOUR ARTICLE BEGINS A FEW INCHES DOWN)... <\/b>\r\n\r\n<iframe src=\"https:\/\/widget.spreaker.com\/player?show_id=3076978&theme=light&playlist=false&playlist-continuous=false&autoplay=false&live-autoplay=false&chapters-image=true&episode_image_position=right&hide-logo=false&hide-likes=false&hide-comments=false&hide-sharing=false&hide-download=true\" width=\"100%\" height=\"140px\" frameborder=\"0\"><\/iframe>\r\n<hr \/><\/div><p><strong>SHOW SUMMARY:\u00a0<\/strong>In this week&#8217;s Interview Classic episode from ten years ago (12-6-2013), Wade Keller interviews ex-WWE Creative Team Member Chris DeJoseph discussing WWE Network plans, WrestleMania 30 line-up, Chris Benoit conspiracies, Stephanie McMahon&#8217;s new title, how Triple H differs from Vince McMahon creatively, and more.<\/p>\n<p>SUPPORT OUR SPONSORS&#8230;<\/p>\n<p>Factor&#8217;s prepared meals designed by chefs and nutritionists. Choose from many custom categories (keto, calorie smart, vegetarian\/vegan, more) delivered to your door, fresh, never frozen, ready in two minutes&#8230;<\/p>\n<p>&#8211;<a href=\"https:\/\/factormeals.com\/wade50\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/factormeals.com\/wade50&amp;source=gmail&amp;ust=1686624379236000&amp;usg=AOvVaw3tejKLhflSw_oRMBGIS-1o\">https:\/\/factormeals.com\/<wbr \/>wade50<\/a> and enter code &#8220;wade50&#8221; for 50 percent off your first box<\/p>\n<p>PWTorch VIP membership&#8230;<\/p>\n<p>&#8211;<a href=\"https:\/\/www.pwtorch.com\/govip\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.pwtorch.com\/govip&amp;source=gmail&amp;ust=1686624379236000&amp;usg=AOvVaw26fGrI_THjG3e49SeEjsvM\">https:\/\/www.pwtorch.com\/govip<\/a><\/p>\n<p>Or support us on Patreon&#8230;<\/p>\n<p>&#8211;<a href=\"https:\/\/www.patreon.com\/pwtorchvip\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.patreon.com\/pwtorchvip&amp;source=gmail&amp;ust=1686624379236000&amp;usg=AOvVaw3HgakJdOKpCZlPjLE9MBPE\">https:\/\/www.patreon.com\/<wbr \/>pwtorchvip<\/a><\/p><div id=\"pwtor-32422904\" class=\"pwtor-content pwtor-entity-placement\"><div align=\"center\" data-freestar-ad=\"__336x280 __336x280\" id=\"pwtorchcom_test_300x250\">\r\n  <script data-cfasync=\"false\" type=\"text\/javascript\">\r\n    freestar.config.enabled_slots.push({ placementName: \"pwtorchcom_test_300x250\", slotId: \"pwtorchcom_test_300x250\" });\r\n  <\/script>\r\n<\/div><\/div>\n<p>Subscribe to our YouTube Channel with new daily content&#8230;<\/p>\n<p>&#8211;<a href=\"https:\/\/www.youtube.com\/pwtorch\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.youtube.com\/pwtorch&amp;source=gmail&amp;ust=1686624379236000&amp;usg=AOvVaw0kjwigphLiEpKWBQJ0uhZ6\">https:\/\/www.youtube.com\/<wbr \/>pwtorch<\/a><\/p>\n<p><strong>DIRECT LINK:\u00a0<\/strong>\u00a0<a href=\"http:\/\/www.pwtorch.com\/android\/legacyuploads\/wp-media\/2023\/12\/20231209WKPWP-IntClassic-VIP.mp3\">VIP AUDIO LINK<\/a><\/p>\n<p><strong>NOT VIP? NO PROBLEM\u2026<\/strong>\u00a0<a href=\"https:\/\/www.pwtorchvipinfo.com\">CLICK HERE FOR VIP SIGN UP INFO<\/a><\/p>\n<div class=\"pwtor-end-article-groups pwtor-entity-placement\" id=\"pwtor-1834322960\"><div id=\"pwtor-611017130\"><div align=\"center\" data-freestar-ad=\"__336x280\" id=\"pwtorchcom_medrec_3\">\r\n  <script data-cfasync=\"false\" type=\"text\/javascript\">\r\n    freestar.config.enabled_slots.push({ placementName: \"pwtorchcom_medrec_3\", slotId: \"pwtorchcom_medrec_3\" });\r\n  <\/script>\r\n<\/div>\r\n\r\nTHANK YOU FOR VISITING<\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>SHOW SUMMARY:\u00a0In this week&#8217;s Interview Classic episode from ten years ago (12-6-2013), Wade Keller interviews ex-WWE Creative Team Member Chris DeJoseph discussing WWE Network plans, WrestleMania 30 line-up, Chris Benoit conspiracies, Stephanie McMahon&#8217;s new title, <a class=\"mh-excerpt-more\" href=\"https:\/\/www.pwtorch.com\/site\/podcast\/vip-audio-12-9-wkpwp-interview-classic-10-yrs-ago-ad-free-ex-wwe-creative-team-member-chris-dejoseph-on-how-triple-h-differs-from-vince-creatively-benoit-conspiracies-stephanies-new\/\" title=\"VIP AUDIO 12\/9 \u2013 WKPWP Interview Classic (10 Yrs Ago) (AD-FREE): Ex-WWE Creative Team Member Chris DeJoseph on how Triple H differs from Vince creatively, Benoit conspiracies, Stephanie&#8217;s new title, WWE Network plans, WM30 line-up (81 min.)\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":135832,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"episode_type":"audio","audio_file":"https:\/\/www.pwtorch.com\/site\/wp-content\/uploads\/podcast\/2023\/12\/20231209WKPWP-IntClassic-VIP.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"1:21:45","filesize":"37.87M","filesize_raw":"39709564","date_recorded":"2023-12-09 01:10:53","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":""},"tags":[],"series":[1037,1018,1202,1034,5889],"class_list":["post-170373","podcast","type-podcast","status-publish","has-post-thumbnail","hentry","series-all-vip-audio-shows","series-analysis","series-all","series-thursdays","series-wkpwp"],"episode_featured_image":"https:\/\/www.pwtorch.com\/site\/wp-content\/uploads\/post\/2022\/03\/WKPWPPodcast2022_VIP.png","episode_player_image":"https:\/\/www.pwtorch.com\/site\/wp-content\/uploads\/2015\/11\/PWTorchVIPAudio2015_1400.png","download_link":"https:\/\/www.pwtorch.com\/site\/podcast-download\/170373\/vip-audio-12-9-wkpwp-interview-classic-10-yrs-ago-ad-free-ex-wwe-creative-team-member-chris-dejoseph-on-how-triple-h-differs-from-vince-creatively-benoit-conspiracies-stephanies-new","player_link":"https:\/\/www.pwtorch.com\/site\/podcast-player\/170373\/vip-audio-12-9-wkpwp-interview-classic-10-yrs-ago-ad-free-ex-wwe-creative-team-member-chris-dejoseph-on-how-triple-h-differs-from-vince-creatively-benoit-conspiracies-stephanies-new","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/www.pwtorch.com\/site\/podcast-player\/170373\/vip-audio-12-9-wkpwp-interview-classic-10-yrs-ago-ad-free-ex-wwe-creative-team-member-chris-dejoseph-on-how-triple-h-differs-from-vince-creatively-benoit-conspiracies-stephanies-new\">https:\/\/www.pwtorch.com\/site\/podcast-player\/170373\/vip-audio-12-9-wkpwp-interview-classic-10-yrs-ago-ad-free-ex-wwe-creative-team-member-chris-dejoseph-on-how-triple-h-differs-from-vince-creatively-benoit-conspiracies-stephanies-new<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"}},"rssFeedUrl":"https:\/\/www.pwtorch.com\/site\/feed\/podcast\/all-vip-audio-shows","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"ZwFlf0UbVZ\"><a href=\"https:\/\/www.pwtorch.com\/site\/podcast\/vip-audio-12-9-wkpwp-interview-classic-10-yrs-ago-ad-free-ex-wwe-creative-team-member-chris-dejoseph-on-how-triple-h-differs-from-vince-creatively-benoit-conspiracies-stephanies-new\/\">VIP AUDIO 12\/9 \u2013 WKPWP Interview Classic (10 Yrs Ago) (AD-FREE): Ex-WWE Creative Team Member Chris DeJoseph on how Triple H differs from Vince creatively, Benoit conspiracies, Stephanie&#8217;s new title, WWE Network plans, WM30 line-up (81 min.)<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/www.pwtorch.com\/site\/podcast\/vip-audio-12-9-wkpwp-interview-classic-10-yrs-ago-ad-free-ex-wwe-creative-team-member-chris-dejoseph-on-how-triple-h-differs-from-vince-creatively-benoit-conspiracies-stephanies-new\/embed\/#?secret=ZwFlf0UbVZ\" width=\"500\" height=\"350\" title=\"&#8220;VIP AUDIO 12\/9 \u2013 WKPWP Interview Classic (10 Yrs Ago) (AD-FREE): Ex-WWE Creative Team Member Chris DeJoseph on how Triple H differs from Vince creatively, Benoit conspiracies, Stephanie&#8217;s new title, WWE Network plans, WM30 line-up (81 min.)&#8221; &#8212; \" data-secret=\"ZwFlf0UbVZ\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/www.pwtorch.com\/site\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/podcast\/170373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/comments?post=170373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/media\/135832"}],"wp:attachment":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/media?parent=170373"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/tags?post=170373"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/series?post=170373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}