{"id":27618,"date":"2016-07-30T09:32:13","date_gmt":"2016-07-30T14:32:13","guid":{"rendered":"http:\/\/www.pwtorch.com\/site\/?p=27618"},"modified":"2016-07-30T11:22:05","modified_gmt":"2016-07-30T16:22:05","slug":"njpw-g1-climax-updated-standings-night-8-july-30","status":"publish","type":"post","link":"https:\/\/www.pwtorch.com\/site\/2016\/07\/30\/njpw-g1-climax-updated-standings-night-8-july-30\/","title":{"rendered":"NJPW G1 Climax Updated Standings &#038; Table Results &#8211; Night 8 (July 30)"},"content":{"rendered":"<div id=\"pwtor-3440274452\" class=\"pwtor-before-content pwtor-entity-placement\"><hr \/><b>SPOTLIGHTED PODCAST ALERT (YOUR ARTICLE BEGINS A FEW INCHES DOWN)... <\/b>\r\n\r\n<iframe src=\"https:\/\/widget.spreaker.com\/player?show_id=3076978&theme=light&playlist=false&playlist-continuous=false&autoplay=false&live-autoplay=false&chapters-image=true&episode_image_position=right&hide-logo=false&hide-likes=false&hide-comments=false&hide-sharing=false&hide-download=true\" width=\"100%\" height=\"140px\" frameborder=\"0\"><\/iframe>\r\n<hr \/><\/div><p><strong>New Japan G1 Climax Standings<\/strong><\/p>\n<p><em>Through <a href=\"http:\/\/www.pwtorch.com\/site\/2016\/07\/30\/730-new-japan-g1-climax-night-8-results-shibata-vs-naito-main-event-elgin-vs-kenny-omega\/\">Night 8 &#8211; July 30<\/a>.<\/em><\/p>\n<p><em>Next: July 31 &#8211; A Block.\u00a0<\/em>(<a href=\"http:\/\/www.pwtorch.com\/site\/g1climax2016\" target=\"_blank\">Full Tournament Central<\/a>)<\/p>\n<p><strong>A Block Standings<\/strong><\/p>\n<ul>\n<li>Togi Makabe (4-0, 8 pts)<\/li>\n<li>IWGP Champ Kazuchika Okada (3-1, 6\u00a0pts)<\/li>\n<li>Tenzan (2-2, 4\u00a0pts)<\/li>\n<li>Hirooki Goto (2-2, 4\u00a0pts)<\/li>\n<li>Tomohiro Ishii (2-2, 4\u00a0pts)<\/li>\n<li>Naomichi Marufuji (2-2, 4\u00a0pts)<\/li>\n<li>Sanada\u00a0(2-2, 4\u00a0pts)<\/li>\n<li>Bad Luck Fale\u00a0(1-3, 2\u00a0pts)<\/li>\n<li>Tama Tonga\u00a0(1-3, 2\u00a0pts)<\/li>\n<li>Hiroshi Tanahashi\u00a0(1-3, 2\u00a0pts)<\/li>\n<\/ul>\n<p><strong>B Block Standings<\/strong><\/p>\n<ul>\n<li>Yuji Nagata (3-1, 6\u00a0pts)<\/li>\n<li>Katsuhiko Nakajima (3-1, 6\u00a0pts)<\/li>\n<li>NEVER Openweight champion Shibata (2-2, 4\u00a0pts)<\/li>\n<li>IWGP IC champion Michael Elgin\u00a0(2-2, 4\u00a0pts)<\/li>\n<li>Honma\u00a0(2-2, 4\u00a0pts)<\/li>\n<li>Kenny Omega\u00a0(2-2, 4\u00a0pts)<\/li>\n<li>Naito\u00a0(2-2, 4\u00a0pts)<\/li>\n<li>YOSHI-HASHI\u00a0(2-2, 4\u00a0pts)<\/li>\n<li>EVIL\u00a0(1-3, 2 pts)<\/li>\n<li>Toru Yano\u00a0(1-3, 2\u00a0pts)<\/li>\n<\/ul>\n\n<table id=\"tablepress-7\" class=\"tablepress tablepress-id-7\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">MATCH<\/th><th class=\"column-2\">DATE<\/th><th class=\"column-3\">WINNER<\/th><th class=\"column-4\">TIME<\/th><th class=\"column-5\">LOSER<\/th><th class=\"column-6\">BLOCK<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">7\/18<\/td><td class=\"column-3\"><strong>Tenzan<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">14:10<br \/>\nPin<\/td><td class=\"column-5\"><em>Tomohiro Ishii<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">7\/18<\/td><td class=\"column-3\"><strong>Togi Makabe<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">10:38<br \/>\nPin<\/td><td class=\"column-5\"><em>Tama Tonga<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">7\/18<\/td><td class=\"column-3\"><strong>Hirooki Goto<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">9:20<br \/>\nPin<\/td><td class=\"column-5\"><em>Bad Luck Fale<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">7\/18<\/td><td class=\"column-3\"><strong>Sanada<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">19:30<br \/>\nTap-out<\/td><td class=\"column-5\"><em>Hiroshi Tanahashi<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">7\/18<\/td><td class=\"column-3\"><strong>Naomichi Marufuji<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">19:08<br \/>\nPin<\/td><td class=\"column-5\"><em>Kazuchika Okada<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">7\/22<\/td><td class=\"column-3\"><strong>Katsuhiko Nakajima<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">3:51<br \/>\nPin<\/td><td class=\"column-5\"><em>Toru Yano<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">7\/22<\/td><td class=\"column-3\"><strong>YOSHI-HASHI<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">12:16<br \/>\nPin<\/td><td class=\"column-5\"><em>Kenny Omega<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">7\/22<\/td><td class=\"column-3\"><strong>EVIL<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">10:54<br \/>\nPin<\/td><td class=\"column-5\"><em>Michael Elgin<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">7\/22<\/td><td class=\"column-3\"><strong>Yuji Nagata<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">15:32<br \/>\nPin<\/td><td class=\"column-5\"><em>Yuji Nagata<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">7\/22<\/td><td class=\"column-3\"><strong>Honma<\/strong><br \/>\n(1-0, 2 pts)<\/td><td class=\"column-4\">11:11<br \/>\nPin<\/td><td class=\"column-5\"><em>Honma<\/em><br \/>\n(0-1, 0 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">7\/23<\/td><td class=\"column-3\"><strong>Tenzan<\/strong><br \/>\n(2-0, 4 pts)<\/td><td class=\"column-4\">10:31<br \/>\nPin<\/td><td class=\"column-5\"><em>Tama Tonga<\/em><br \/>\n(0-2, 0 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">7\/23<\/td><td class=\"column-3\"><strong>Hirooki Goto<\/strong><br \/>\n(2-0, 4 pts)<\/td><td class=\"column-4\">11:49<br \/>\nPin<\/td><td class=\"column-5\"><em>Tomohiro Ishii<\/em><br \/>\n(0-2, 0 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">7\/23<\/td><td class=\"column-3\"><strong>Bad Luck Fale<\/strong><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-4\">9:36<br \/>\nPin<\/td><td class=\"column-5\"><em>Naomichi Marufuji<\/em><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">7\/23<\/td><td class=\"column-3\"><strong>Kazuchika Okada<\/strong><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-4\">13:20<br \/>\nPin<\/td><td class=\"column-5\"><em>Sanada<\/em><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">7\/23<\/td><td class=\"column-3\"><strong>Togi Makabe<\/strong><br \/>\n(2-0, 4 pts)<\/td><td class=\"column-4\">14:04<br \/>\nPin<\/td><td class=\"column-5\"><em>Tanahashi<\/em><br \/>\n(0-2, 0 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">7\/24<\/td><td class=\"column-3\"><strong>Honma<\/strong><br \/>\n(2-0, 4 pts)<\/td><td class=\"column-4\">13:07<br \/>\nPin<\/td><td class=\"column-5\"><em>YOSHI-HASHI<\/em><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">7\/24<\/td><td class=\"column-3\"><strong>Yuji Nagata<\/strong><br \/>\n(2-0, 4 pts)<\/td><td class=\"column-4\">10:54<br \/>\nPin<\/td><td class=\"column-5\"><em>EVIL<\/em><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">7\/24<\/td><td class=\"column-3\"><strong>Kenny Omega<\/strong><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-4\">9:05<br \/>\nPin<\/td><td class=\"column-5\"><em>Toru Yano<\/em><br \/>\n(0-2, 0 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">7\/24<\/td><td class=\"column-3\"><strong>Shibata<\/strong><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-4\">14:08<br \/>\nPin<\/td><td class=\"column-5\"><em>Katsuhiko Nakajima<\/em><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">7\/24<\/td><td class=\"column-3\"><strong>Naito<\/strong><br \/>\n(1-1, 2 pts)<\/td><td class=\"column-4\">22:12<br \/>\nPin<\/td><td class=\"column-5\"><em>Michael Elgin<\/em><br \/>\n(0-2, 0 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">7\/25<\/td><td class=\"column-3\"><strong>Tomohiro Ishii<\/strong><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-4\">9:35<br \/>\nPin<\/td><td class=\"column-5\"><em>Bad Luck Fale<\/em><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">7\/25<\/td><td class=\"column-3\"><strong>Togi Makabe<\/strong><br \/>\n(3-0, 6 pts)<\/td><td class=\"column-4\">12:25<br \/>\nPin<\/td><td class=\"column-5\"><em>Sanada<\/em><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">7\/25<\/td><td class=\"column-3\"><strong>Naomichi Marufuji<\/strong><br \/>\n(2-1, 4 pts)<\/td><td class=\"column-4\">12:29<br \/>\nPin<\/td><td class=\"column-5\"><em>Tenzan<\/em><br \/>\n(2-1, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">7\/25<\/td><td class=\"column-3\"><strong>Tama Tonga<\/strong><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-4\">11:10<br \/>\nPin<\/td><td class=\"column-5\"><em>Tanahashi<\/em><br \/>\n(0-3, 0 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">7\/25<\/td><td class=\"column-3\"><strong>Kazuchika Okada<\/strong><br \/>\n(2-1, 4 pts)<\/td><td class=\"column-4\">16:11<br \/>\nPin<\/td><td class=\"column-5\"><em>Hirooki Goto<\/em><br \/>\n(2-1, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">7\/27<\/td><td class=\"column-3\"><strong>Yuji Nagata<\/strong><br \/>\n(3-0, 6 pts)<\/td><td class=\"column-4\">11:56<br \/>\nPin<\/td><td class=\"column-5\"><em>YOSHI-HASHI<\/em><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">27<\/td><td class=\"column-2\">7\/27<\/td><td class=\"column-3\"><strong>Katsuhiko Nakajima<\/strong><br \/>\n(2-1, 4 pts)<\/td><td class=\"column-4\">10:31<br \/>\nPin<\/td><td class=\"column-5\"><em>EVIL<\/em><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">7\/27<\/td><td class=\"column-3\"><strong>Naito<\/strong><br \/>\n(2-1, 4 pts)<\/td><td class=\"column-4\">4:54<br \/>\nPin<\/td><td class=\"column-5\"><em>Toru Yano<\/em><br \/>\n(0-3, 0 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">29<\/td><td class=\"column-2\">7\/27<\/td><td class=\"column-3\"><strong>Kenny Omega<\/strong><br \/>\n(2-1, 4 pts)<\/td><td class=\"column-4\">13:59<br \/>\nPin<\/td><td class=\"column-5\"><em>Honma<\/em><br \/>\n(2-1, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">7\/27<\/td><td class=\"column-3\"><strong>Michael Elgin<\/strong><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-4\">15:53<br \/>\nPin<\/td><td class=\"column-5\"><em>Shibata<\/em><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">31<\/td><td class=\"column-2\">7\/28<\/td><td class=\"column-3\"><strong>Togi Makabe<\/strong><br \/>\n(4-0, 8 pts)<\/td><td class=\"column-4\">10:08<br \/>\nPin<\/td><td class=\"column-5\"><em>Tenzan<\/em><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">32<\/td><td class=\"column-2\">7\/28<\/td><td class=\"column-3\"><strong>Sanada<\/strong><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-4\">12:05<br \/>\nPin<\/td><td class=\"column-5\"><em>Hirooki Goto<\/em><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">33<\/td><td class=\"column-2\">7\/28<\/td><td class=\"column-3\"><strong>Tomohiro Ishii<\/strong><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-4\">12:14<br \/>\nPin<\/td><td class=\"column-5\"><em>Naomichi Marufuji<\/em><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">34<\/td><td class=\"column-2\">7\/28<\/td><td class=\"column-3\"><strong>Kazuchika Okada<\/strong><br \/>\n(3-1, 6 pts)<\/td><td class=\"column-4\">11:45<br \/>\nPin<\/td><td class=\"column-5\"><em>Tama Tonga<\/em><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">35<\/td><td class=\"column-2\">7\/28<\/td><td class=\"column-3\"><strong>Tanahashi<\/strong><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-4\">15:05<br \/>\nPin<\/td><td class=\"column-5\"><em>Bad Luck Fale<\/em><br \/>\n(1-2, 2 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">36<\/td><td class=\"column-2\">7\/30<\/td><td class=\"column-3\"><strong>Toru Yano<\/strong><br \/>\n(1-3, 2 pts)<\/td><td class=\"column-4\">4:21<br \/>\nPin<\/td><td class=\"column-5\"><em>Honma<\/em><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">37<\/td><td class=\"column-2\">7\/30<\/td><td class=\"column-3\"><strong>YOSHI-HASHI<\/strong><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-4\">12:48<br \/>\nPin<\/td><td class=\"column-5\"><em>EVIL<\/em><br \/>\n(1-3, 2 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">38<\/td><td class=\"column-2\">7\/30<\/td><td class=\"column-3\"><strong>Katsuhiko Nakajima<\/strong><br \/>\n(3-1, 6 pts)<\/td><td class=\"column-4\">12:32<br \/>\nPin<\/td><td class=\"column-5\"><em>Yuji Nagata<\/em><br \/>\n(3-1, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">39<\/td><td class=\"column-2\">7\/30<\/td><td class=\"column-3\"><strong>Michael Elgin<\/strong><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-4\">16:44<br \/>\nPin<\/td><td class=\"column-5\"><em>Kenny Omega<\/em><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">40<\/td><td class=\"column-2\">7\/30<\/td><td class=\"column-3\"><strong>Shibata<\/strong><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-4\">19:24<br \/>\nSleeper<\/td><td class=\"column-5\"><em>Naito<\/em><br \/>\n(2-2, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">41<\/td><td class=\"column-2\">7\/31<\/td><td class=\"column-3\"><strong>Tama Tonga<\/strong><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-4\">11:00<br \/>\nPin<\/td><td class=\"column-5\"><em>Tomohiro Ishii<\/em><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">42<\/td><td class=\"column-2\">7\/31<\/td><td class=\"column-3\"><strong>Bad Luck Fale<\/strong><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-4\">9:06<br \/>\nPin<\/td><td class=\"column-5\"><em>Sanada<\/em><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">43<\/td><td class=\"column-2\">7\/31<\/td><td class=\"column-3\"><strong>Naomichi Marufuji<\/strong><br \/>\n(3-2, 6 pts)<\/td><td class=\"column-4\">10:39<br \/>\nPin<\/td><td class=\"column-5\"><em>Togi Makabe<\/em><br \/>\n(4-1, 8 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">44<\/td><td class=\"column-2\">7\/31<\/td><td class=\"column-3\"><strong>Kazuchika Okada<\/strong><br \/>\n(4-1, 8 pts)<\/td><td class=\"column-4\">12:30<br \/>\nPin<\/td><td class=\"column-5\"><em>Tenzan<\/em><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">45<\/td><td class=\"column-2\">7\/31<\/td><td class=\"column-3\"><strong>Tanahashi<\/strong><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-4\">17:47<br \/>\nPin<\/td><td class=\"column-5\"><em>Hirooki Goto<\/em><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">46<\/td><td class=\"column-2\">8\/1<\/td><td class=\"column-3\"><strong>YOSHI-HASHI<\/strong><br \/>\n(3-2, 6 pts)<\/td><td class=\"column-4\">12:02<br \/>\nPin<\/td><td class=\"column-5\"><em>Katsuhiko Nakajima<\/em><br \/>\n(3-2, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">47<\/td><td class=\"column-2\">8\/1<\/td><td class=\"column-3\"><strong>Michael Elgin<\/strong><br \/>\n(3-2, 6 pts)<\/td><td class=\"column-4\">10:35<br \/>\nPin<\/td><td class=\"column-5\"><em>Yuji Nagata<\/em><br \/>\n(3-2, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">48<\/td><td class=\"column-2\">8\/1<\/td><td class=\"column-3\"><strong>Toru Yano<\/strong><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-4\">1:05<br \/>\nPin<\/td><td class=\"column-5\"><em>Shibata<\/em><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">49<\/td><td class=\"column-2\">8\/1<\/td><td class=\"column-3\"><strong>Kenny Omega<\/strong><br \/>\n(3-2, 6 pts)<\/td><td class=\"column-4\">10:15<br \/>\nPin<\/td><td class=\"column-5\"><em>EVIL<\/em><br \/>\n(1-4, 2 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">50<\/td><td class=\"column-2\">8\/1<\/td><td class=\"column-3\"><strong>Naito<\/strong><br \/>\n(3-2, 6 pts)<\/td><td class=\"column-4\">20:38<br \/>\nPin<\/td><td class=\"column-5\"><em>Honma<\/em><br \/>\n(2-3, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">51<\/td><td class=\"column-2\">8\/3<\/td><td class=\"column-3\"><strong>Bad Luck Fale<\/strong><br \/>\n(3-3, 6 pts)<\/td><td class=\"column-4\">8:22<br \/>\nPin<\/td><td class=\"column-5\"><em>Tenzan<\/em><br \/>\n(2-4, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">52<\/td><td class=\"column-2\">8\/3<\/td><td class=\"column-3\"><strong>Hirooki Goto<\/strong><br \/>\n(3-3, 6 pts)<\/td><td class=\"column-4\">12:29<br \/>\nPin<\/td><td class=\"column-5\"><em>Tama Tonga<\/em><br \/>\n(2-4, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">53<\/td><td class=\"column-2\">8\/3<\/td><td class=\"column-3\"><strong>Naomichi Marufuji<\/strong><br \/>\n(4-2, 8 pts)<\/td><td class=\"column-4\">10:39<br \/>\nPin<\/td><td class=\"column-5\"><em>Sanada<\/em><br \/>\n(2-4, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">54<\/td><td class=\"column-2\">8\/3<\/td><td class=\"column-3\"><strong>Tanahashi<\/strong><br \/>\n(3-3, 6 pts)<\/td><td class=\"column-4\">16:10<br \/>\nPin<\/td><td class=\"column-5\"><em>Tomohiro Ishii<\/em><br \/>\n(2-4, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">55<\/td><td class=\"column-2\">8\/3<\/td><td class=\"column-3\"><strong>Kazuchika Okada<\/strong><br \/>\n(5-1, 10 pts)<\/td><td class=\"column-4\">15:04<br \/>\nPin<\/td><td class=\"column-5\"><em>Togi Makabe<\/em><br \/>\n(4-2, 8 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">56<\/td><td class=\"column-2\">8\/4<\/td><td class=\"column-3\"><strong>Toru Yano<\/strong><br \/>\n(3-3, 6 pts)<\/td><td class=\"column-4\">4:22<br \/>\nCountout<\/td><td class=\"column-5\"><em>Yuji Nagata<\/em><br \/>\n(3-3, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">57<\/td><td class=\"column-2\">8\/4<\/td><td class=\"column-3\"><strong>Michael Elgin<\/strong><br \/>\n(4-2, 8 pts)<\/td><td class=\"column-4\">9:49<br \/>\nPin<\/td><td class=\"column-5\"><em>YOSHI-HASHI<\/em><br \/>\n(3-3, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\">58<\/td><td class=\"column-2\">8\/4<\/td><td class=\"column-3\"><strong>EVIL<\/strong><br \/>\n(2-4, 4 pts)<\/td><td class=\"column-4\">9:49<br \/>\nPin<\/td><td class=\"column-5\"><em>Honma<\/em><br \/>\n(2-4, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">59<\/td><td class=\"column-2\">8\/4<\/td><td class=\"column-3\"><strong>Shibata<\/strong><br \/>\n(3-3, 6 pts)<\/td><td class=\"column-4\">12:28<br \/>\nPin<\/td><td class=\"column-5\"><em>Kenny Omega<\/em><br \/>\n(3-3, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\">60<\/td><td class=\"column-2\">8\/4<\/td><td class=\"column-3\"><strong>Naito<\/strong><br \/>\n(4-2, 8 pts)<\/td><td class=\"column-4\">19:08<br \/>\nPin<\/td><td class=\"column-5\"><em>Katsuhiko Nakajima<\/em><br \/>\n(3-3, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">61<\/td><td class=\"column-2\">8\/6<\/td><td class=\"column-3\"><strong>Tama Tonga<\/strong><br \/>\n(3-4, 6 pts)<\/td><td class=\"column-4\">10:40<br \/>\nPin<\/td><td class=\"column-5\"><em>Sanada<\/em><br \/>\n(2-5, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\">62<\/td><td class=\"column-2\">8\/6<\/td><td class=\"column-3\"><strong>Bad Luck Fale<\/strong><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-4\">8:38<br \/>\nPin<\/td><td class=\"column-5\"><em>Togi Makabe<\/em><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\">63<\/td><td class=\"column-2\">8\/6<\/td><td class=\"column-3\"><strong>Hirooki Goto<\/strong><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-4\">10:02<br \/>\nPin<\/td><td class=\"column-5\"><em>Tenzan<\/em><br \/>\n(2-5, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">64<\/td><td class=\"column-2\">8\/6<\/td><td class=\"column-3\"><strong>Tomohiro Ishii<\/strong><br \/>\n(3-4, 6 pts)<\/td><td class=\"column-4\">18:43<br \/>\nPin<\/td><td class=\"column-5\"><em>Kazuchika Okada<\/em><br \/>\n(5-2, 10 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td class=\"column-1\">65<\/td><td class=\"column-2\">8\/6<\/td><td class=\"column-3\"><strong>Tanahashi<\/strong><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-4\">19:00<br \/>\nPin<\/td><td class=\"column-5\"><em>Naomichi Marufuji<\/em><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\">66<\/td><td class=\"column-2\">8\/7<\/td><td class=\"column-3\"><strong>Toru Yano<\/strong><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-4\">4:59<br \/>\nPin<\/td><td class=\"column-5\"><em>Michael Elgin<\/em><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">67<\/td><td class=\"column-2\">8\/7<\/td><td class=\"column-3\"><strong>Shibata<\/strong><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-4\">11:08<br \/>\nPin<\/td><td class=\"column-5\"><em>YOSHI-HASHI<\/em><br \/>\n(3-4, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\">68<\/td><td class=\"column-2\">8\/7<\/td><td class=\"column-3\"><strong>Katsuhiko Nakajima<\/strong><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-4\">12:34<br \/>\nPin<\/td><td class=\"column-5\"><em>Honma<\/em><br \/>\n(2-5, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\">69<\/td><td class=\"column-2\">8\/7<\/td><td class=\"column-3\"><strong>Kenny Omega<\/strong><br \/>\n(4-3, 8 pts)<\/td><td class=\"column-4\">14:17<br \/>\nPin<\/td><td class=\"column-5\"><em>Yuji Nagata<\/em><br \/>\n(3-4, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-71\">\n\t<td class=\"column-1\">70<\/td><td class=\"column-2\">8\/7<\/td><td class=\"column-3\"><strong>Naito<\/strong><br \/>\n(5-2, 10 pts)<\/td><td class=\"column-4\">21:28<br \/>\nPin<\/td><td class=\"column-5\"><em>EVIL<\/em><br \/>\n(2-5, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-72\">\n\t<td class=\"column-1\">71<\/td><td class=\"column-2\">8\/8<\/td><td class=\"column-3\"><strong>Naomichi Marufuji<\/strong><br \/>\n(5-3, 10 pts)<\/td><td class=\"column-4\">10:54<br \/>\nPin<\/td><td class=\"column-5\"><em>Tama Tonga<\/em><br \/>\n(3-5, 6 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-73\">\n\t<td class=\"column-1\">72<\/td><td class=\"column-2\">8\/8<\/td><td class=\"column-3\"><strong>Sanada<\/strong><br \/>\n(3-5, 6 pts)<\/td><td class=\"column-4\">12:18<br \/>\nSubmit<\/td><td class=\"column-5\"><em>Tomohiro Ishii<\/em><br \/>\n(3-5, 6 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-74\">\n\t<td class=\"column-1\">73<\/td><td class=\"column-2\">8\/8<\/td><td class=\"column-3\"><strong>Tanahashi<\/strong><br \/>\n(5-3, 10 pts)<\/td><td class=\"column-4\">11:17<br \/>\nPin<\/td><td class=\"column-5\"><em>Tenzan<\/em><br \/>\n(2-6, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-75\">\n\t<td class=\"column-1\">74<\/td><td class=\"column-2\">8\/8<\/td><td class=\"column-3\"><strong>Bad Luck Fale<\/strong><br \/>\n(5-3, 10 pts)<\/td><td class=\"column-4\">11:16<br \/>\nPin<\/td><td class=\"column-5\"><em>Kazuchika Okada<\/em><br \/>\n(5-3, 10 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-76\">\n\t<td class=\"column-1\">75<\/td><td class=\"column-2\">8\/8<\/td><td class=\"column-3\"><strong>Hirooki Goto<\/strong><br \/>\n(5-3, 10 pts)<\/td><td class=\"column-4\">14:12<br \/>\nPin<\/td><td class=\"column-5\"><em>Togi Makabe<\/em><br \/>\n(4-4, 8 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-77\">\n\t<td class=\"column-1\">76<\/td><td class=\"column-2\">8\/10<\/td><td class=\"column-3\"><strong>Kenny Omega<\/strong><br \/>\n(5-3, 10 pts)<\/td><td class=\"column-4\">10:29<br \/>\nPin<\/td><td class=\"column-5\"><em>Nakajima<\/em><br \/>\n(4-4, 8 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-78\">\n\t<td class=\"column-1\">77<\/td><td class=\"column-2\">8\/10<\/td><td class=\"column-3\"><strong>EVIL<\/strong><br \/>\n(3-5, 6 pts)<\/td><td class=\"column-4\">2:57<br \/>\nPin<\/td><td class=\"column-5\"><em>Toru Yano<\/em><br \/>\n(4-4, 8 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-79\">\n\t<td class=\"column-1\">78<\/td><td class=\"column-2\">8\/10<\/td><td class=\"column-3\"><strong>Naito<\/strong><br \/>\n(6-2, 12 pts)<\/td><td class=\"column-4\">15:01<br \/>\nPin<\/td><td class=\"column-5\"><em>YOSHI-HASHI<\/em><br \/>\n(3-5, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-80\">\n\t<td class=\"column-1\">79<\/td><td class=\"column-2\">8\/10<\/td><td class=\"column-3\"><strong>Shibata<\/strong><br \/>\n(5-3, 10 pts)<\/td><td class=\"column-4\">12:16<br \/>\nSleeper<\/td><td class=\"column-5\"><em>Yuji Nagata<\/em><br \/>\n(3-5, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-81\">\n\t<td class=\"column-1\">80<\/td><td class=\"column-2\">8\/10<\/td><td class=\"column-3\"><strong>Michael Elgin<\/strong><br \/>\n(5-3, 10 pts)<\/td><td class=\"column-4\">18:43<br \/>\nPin<\/td><td class=\"column-5\"><em>Honma<\/em><br \/>\n(2-6, 4 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-82\">\n\t<td class=\"column-1\">81<\/td><td class=\"column-2\">8\/12<\/td><td class=\"column-3\"><strong>Sanada<\/strong><br \/>\n(4-5, 10 pts)<\/td><td class=\"column-4\">12:12<br \/>\nPin<\/td><td class=\"column-5\"><em>Tenzan<\/em><br \/>\n(2-7, 4 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-83\">\n\t<td class=\"column-1\">82<\/td><td class=\"column-2\">8\/12<\/td><td class=\"column-3\"><strong>Tomohiro Ishii<\/strong><br \/>\n(4-5, 10 pts)<\/td><td class=\"column-4\">12:33<br \/>\nPin<\/td><td class=\"column-5\"><em>Togi Makabe<\/em><br \/>\n(4-5, 10 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-84\">\n\t<td class=\"column-1\">83<\/td><td class=\"column-2\">8\/12<\/td><td class=\"column-3\"><strong>Tama Tonga<\/strong><br \/>\n(4-5, 10 pts)<\/td><td class=\"column-4\">8:39<br \/>\nPin<\/td><td class=\"column-5\"><em>Bad Luck Fale<\/em><br \/>\n(5-4, 10 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-85\">\n\t<td class=\"column-1\">84<\/td><td class=\"column-2\">8\/12<\/td><td class=\"column-3\"><strong>Hirooki Goto<\/strong><br \/>\n(6-3, 12 pts)<br \/>\nA BLOCK WINNER<\/td><td class=\"column-4\">13:17<br \/>\nPin<\/td><td class=\"column-5\"><em>Naomichi Marufuji<\/em><br \/>\n(5-4, 10 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-86\">\n\t<td class=\"column-1\">85<\/td><td class=\"column-2\">8\/12<\/td><td class=\"column-3\"><u>Kazuchika Okada<\/u><br \/>\n(5-3-1, 11 pts)<\/td><td class=\"column-4\">30:00<br \/>\nDraw<\/td><td class=\"column-5\"><u>Hiroshi Tanahashi<\/u><br \/>\n(5-3-1, 11 pts)<\/td><td class=\"column-6\">A Block<\/td>\n<\/tr>\n<tr class=\"row-87\">\n\t<td class=\"column-1\">86<\/td><td class=\"column-2\">8\/13<\/td><td class=\"column-3\"><strong>Honma<\/strong><br \/>\n(3-6, 6 pts)<\/td><td class=\"column-4\">10:29<br \/>\nPin<\/td><td class=\"column-5\"><em>Yuji Nagata<\/em><br \/>\n(3-6, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-88\">\n\t<td class=\"column-1\">87<\/td><td class=\"column-2\">8\/13<\/td><td class=\"column-3\"><strong>Toru Yano<\/strong><br \/>\n(5-4, 10 pts)<\/td><td class=\"column-4\">3:31<br \/>\nPin<\/td><td class=\"column-5\"><em>YOSHI-HASHI<\/em><br \/>\n(3-6, 6 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-89\">\n\t<td class=\"column-1\">88<\/td><td class=\"column-2\">8\/13<\/td><td class=\"column-3\"><strong>EVIL<\/strong><br \/>\n(4-5, 8 pts)<\/td><td class=\"column-4\">9:42<br \/>\nPin<\/td><td class=\"column-5\"><em>Shibata<\/em><br \/>\n(5-4, 10 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-90\">\n\t<td class=\"column-1\">89<\/td><td class=\"column-2\">8\/13<\/td><td class=\"column-3\"><strong>Katsuhiko Nakajima<\/strong><br \/>\n(5-4, 10 pts)<\/td><td class=\"column-4\">16:50<br \/>\nPin<\/td><td class=\"column-5\"><em>Michael Elgin<\/em><br \/>\n(5-4, 10 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-91\">\n\t<td class=\"column-1\">90<\/td><td class=\"column-2\">8\/13<\/td><td class=\"column-3\"><strong>Kenny Omega<\/strong><br \/>\n(6-3, 12 pts)<br \/>\nB BLOCK WINNER<\/td><td class=\"column-4\">28:12<br \/>\nPin<\/td><td class=\"column-5\"><em>Naito<\/em><br \/>\n(6-3, 12 pts)<\/td><td class=\"column-6\">B Block<\/td>\n<\/tr>\n<tr class=\"row-92\">\n\t<td class=\"column-1\">91<\/td><td class=\"column-2\">8\/14<\/td><td class=\"column-3\"><strong>Kenny Omega<\/strong><br \/>\n(B Block Winner)<br \/>\n(G1 CLIMAX WINNER)<\/td><td class=\"column-4\">26:40<br \/>\nPin<\/td><td class=\"column-5\"><em>Hirooki Goto<\/em><br \/>\n(A Block Winner)<\/td><td class=\"column-6\">G1 CLIMAX<br \/>\nFINALS<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-7 from cache -->\n<div class=\"pwtor-end-article-groups pwtor-entity-placement\" id=\"pwtor-2378395346\"><div id=\"pwtor-4084638289\"><div align=\"center\" data-freestar-ad=\"__336x280\" id=\"pwtorchcom_medrec_3\">\r\n  <script data-cfasync=\"false\" type=\"text\/javascript\">\r\n    freestar.config.enabled_slots.push({ placementName: \"pwtorchcom_medrec_3\", slotId: \"pwtorchcom_medrec_3\" });\r\n  <\/script>\r\n<\/div>\r\n\r\nTHANK YOU FOR VISITING<\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>New Japan G1 Climax Standings Through Night 8 &#8211; July 30. Next: July 31 &#8211; A Block.\u00a0(Full Tournament Central) A Block Standings Togi Makabe (4-0, 8 pts) IWGP Champ Kazuchika Okada (3-1, 6\u00a0pts) Tenzan (2-2, <a class=\"mh-excerpt-more\" href=\"https:\/\/www.pwtorch.com\/site\/2016\/07\/30\/njpw-g1-climax-updated-standings-night-8-july-30\/\" title=\"NJPW G1 Climax Updated Standings &#038; Table Results &#8211; Night 8 (July 30)\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":24107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[3256,3173,87,3486,3258,3487,404,3267,3257,3449],"class_list":["post-27618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news_japan","tag-g1-climax","tag-g1-climax-2016","tag-new-japan","tag-new-japan-events","tag-new-japan-g1-climax","tag-new-japan-g1-climax-2016","tag-njpw","tag-njpw-events","tag-njpw-g1-climax","tag-njpw-g1-climax-2016"],"jetpack_featured_media_url":"https:\/\/www.pwtorch.com\/site\/wp-content\/uploads\/post\/2016\/06\/G1Climax2016.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/posts\/27618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/comments?post=27618"}],"version-history":[{"count":3,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/posts\/27618\/revisions"}],"predecessor-version":[{"id":27629,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/posts\/27618\/revisions\/27629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/media\/24107"}],"wp:attachment":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/media?parent=27618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/categories?post=27618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/tags?post=27618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}