{"id":4805,"count":5,"description":"","link":"https:\/\/www.pwtorch.com\/site\/tag\/laurel-van-ness\/","name":"laurel van ness","slug":"laurel-van-ness","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/tags\/4805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/posts?tags=4805"},{"href":"https:\/\/www.pwtorch.com\/site\/wp-json\/wp\/v2\/podcast?tags=4805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}